{"id":762,"date":"2020-12-29T11:54:57","date_gmt":"2020-12-29T09:54:57","guid":{"rendered":"https:\/\/www.cacbgi.cat\/?post_type=edar&#038;p=762"},"modified":"2026-08-18T12:02:03","modified_gmt":"2026-08-18T10:02:03","slug":"cadaques","status":"publish","type":"edar","link":"https:\/\/www.cacbgi.cat\/es\/edar\/cadaques\/","title":{"rendered":"EDAR Cadaqu\u00e9s"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"762\" class=\"elementor elementor-762\" data-elementor-post-type=\"edar\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c50870d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c50870d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17e1509\" data-id=\"17e1509\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72e85fd dce_masking-none elementor-widget elementor-widget-image\" data-id=\"72e85fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"CADAQUES-e1777376033851\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTEwMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5jYWNiZ2kuY2F0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wNVwvQ0FEQVFVRVMtZTE3NzczNzYwMzM4NTEucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1656\" height=\"724\" src=\"https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851.png\" class=\"attachment-full size-full wp-image-9102\" alt=\"\" srcset=\"https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851.png 1656w, https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851-300x131.png 300w, https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851-1024x448.png 1024w, https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851-768x336.png 768w, https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851-1536x672.png 1536w, https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2026\/05\/CADAQUES-e1777376033851-18x8.png 18w\" sizes=\"(max-width: 1656px) 100vw, 1656px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":764,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tipus":[12],"class_list":["post-762","edar","type-edar","status-publish","has-post-thumbnail","hentry","tipus-zona-nord"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar"}],"about":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/types\/edar"}],"version-history":[{"count":62,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/762\/revisions"}],"predecessor-version":[{"id":9565,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/762\/revisions\/9565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/media\/764"}],"wp:attachment":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"tipus","embeddable":true,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/tipus?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}