{"id":884,"date":"2020-12-29T16:40:21","date_gmt":"2020-12-29T14:40:21","guid":{"rendered":"https:\/\/www.cacbgi.cat\/?post_type=edar&#038;p=884"},"modified":"2026-08-18T12:15:08","modified_gmt":"2026-08-18T10:15:08","slug":"abastament-en-alta-a-la-costa-brava-sud","status":"publish","type":"edar","link":"https:\/\/www.cacbgi.cat\/es\/edar\/abastament-en-alta-a-la-costa-brava-sud\/","title":{"rendered":"Abastament en alta a la Costa Brava Sud"},"content":{"rendered":"<p><a href=\"https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2020\/12\/Fulleto-ETAP-Tossa-Lloret-any-2002.pdf\">Descarrega el fullet\u00f3<\/a><\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tipus":[10,18],"class_list":["post-884","edar","type-edar","status-publish","hentry","tipus-abastaments","tipus-zona-sud-abastaments"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar"}],"about":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/types\/edar"}],"version-history":[{"count":53,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/884\/revisions"}],"predecessor-version":[{"id":9581,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/884\/revisions\/9581"}],"wp:attachment":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/media?parent=884"}],"wp:term":[{"taxonomy":"tipus","embeddable":true,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/tipus?post=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}