{"id":904,"date":"2020-12-29T17:03:42","date_gmt":"2020-12-29T15:03:42","guid":{"rendered":"https:\/\/www.cacbgi.cat\/?post_type=edar&#038;p=904"},"modified":"2026-08-18T12:17:04","modified_gmt":"2026-08-18T10:17:04","slug":"colera-2","status":"publish","type":"edar","link":"https:\/\/www.cacbgi.cat\/es\/edar\/colera-2\/","title":{"rendered":"ERA Colera"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone wp-image-905 size-full\" src=\"https:\/\/www.cacbgi.cat\/wp-content\/uploads\/2020\/12\/nord-1.png\" alt=\"\" width=\"275\" height=\"98\" \/><\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tipus":[9,19],"class_list":["post-904","edar","type-edar","status-publish","hentry","tipus-regeneracio","tipus-zona-nord-regeneracio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar"}],"about":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/types\/edar"}],"version-history":[{"count":49,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/904\/revisions"}],"predecessor-version":[{"id":9585,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/edar\/904\/revisions\/9585"}],"wp:attachment":[{"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/media?parent=904"}],"wp:term":[{"taxonomy":"tipus","embeddable":true,"href":"https:\/\/www.cacbgi.cat\/es\/wp-json\/wp\/v2\/tipus?post=904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}